{"id":2239,"date":"2023-03-02T16:07:34","date_gmt":"2023-03-02T16:07:34","guid":{"rendered":"https:\/\/www.astreitalia.it\/?p=2239"},"modified":"2023-03-02T16:07:34","modified_gmt":"2023-03-02T16:07:34","slug":"autotrasporto-nuova-tranche-di-incentivi-per-lacquisto-di-mezzi-ecologici","status":"publish","type":"post","link":"https:\/\/www.astreitalia.it\/index.php\/2023\/03\/02\/autotrasporto-nuova-tranche-di-incentivi-per-lacquisto-di-mezzi-ecologici\/","title":{"rendered":"Autotrasporto: nuova tranche di incentivi per l&#8217;acquisto di mezzi ecologici"},"content":{"rendered":"<p><strong>Il 15 marzo 2023<\/strong> parte il secondo periodo di <strong>incentivazione<\/strong> all\u2019acquisto mezzi ad <strong>elevata sostenibilit\u00e0 ecologica ad alimentazione alternativa <\/strong>nel settore autotrasporto. Lo stanziamento \u00e8 di 10 milioni di euro.<br \/>\nGli incentivi puntano al rinnovo e e all&#8217;<strong>adeguamento tecnologico del parco veicolare delle imprese di autotrasporto <\/strong>e riguardano nello specifico veicoli commerciali nuovi di fabbrica a trazione alternativa a metano <strong>CNG<\/strong>, gas naturale liquefatto <strong>LNG<\/strong>, ibrida (diesel\/elettrica) e elettrica (full electric).<\/p>\n<p>La norma ha stanziato 50 milioni di euro ripartiti lungo l&#8217;arco temporale 2021-2026: in questo secondo periodo di incentivazione (il primo si \u00e8 chiuso il 16 agosto 2022) le somme accantonate ammontano a 10 milioni e sar\u00e0 possibile <strong>presentare le istanze di richiesta nel periodo compreso tra il 15 marzo ed il 28 aprile 2023.<\/strong><\/p>\n<p>Le richieste devono essere presentate esclusivamente tramite posta elettronica certificata dell\u2019impresa richiedente e indirizzate a ram.investimentielevatasostenibilita@legalmail.it a partire dalle ore 10:00 del 15 marzo 2023 e fino e non oltre le ore 16:00 del 28 aprile 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 15 marzo 2023 parte il secondo periodo di incentivazione all\u2019acquisto mezzi ad elevata sostenibilit\u00e0 ecologica ad alimentazione alternativa nel settore autotrasporto. Lo stanziamento \u00e8 di 10 milioni di euro. Gli incentivi puntano al rinnovo e e all&#8217;adeguamento tecnologico del parco veicolare delle imprese di&#8230;<\/p>\n","protected":false},"author":5,"featured_media":2240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[240,64,241],"class_list":["post-2239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news_esterne","tag-alimentazione-alternativa","tag-ecoincentivi","tag-mezzi-ecologici"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/posts\/2239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/comments?post=2239"}],"version-history":[{"count":2,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/posts\/2239\/revisions"}],"predecessor-version":[{"id":2242,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/posts\/2239\/revisions\/2242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/media\/2240"}],"wp:attachment":[{"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/media?parent=2239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/categories?post=2239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/tags?post=2239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}