{"id":2225,"date":"2023-02-23T15:03:20","date_gmt":"2023-02-23T15:03:20","guid":{"rendered":"https:\/\/www.astreitalia.it\/?p=2225"},"modified":"2023-02-23T15:03:20","modified_gmt":"2023-02-23T15:03:20","slug":"gnl-in-gazzetta-il-decreto-che-disciplina-le-modalita-di-erogazione-del-credito-dimposta","status":"publish","type":"post","link":"https:\/\/www.astreitalia.it\/index.php\/2023\/02\/23\/gnl-in-gazzetta-il-decreto-che-disciplina-le-modalita-di-erogazione-del-credito-dimposta\/","title":{"rendered":"GNL: in Gazzetta il decreto che disciplina le modalit\u00e0 di erogazione del credito d\u2019imposta"},"content":{"rendered":"<p>Pubblicato in Gazzetta Ufficiale il decreto interministeriale con le \u201cMisure urgenti per il contenimento dei costi dell\u2019energia elettrica e del gas naturale per lo sviluppo di energie rinnovabili e per il rilancio delle politiche industriali \u2013 Anno 2022&#8243;.<\/p>\n<p>Il provvedimento stanzia <strong>25 milioni di euro destinate alle imprese aventi sede legale o stabile organizzazione in Italia<\/strong>, iscritte al Registro elettronico nazionale (R.E.N.) e all\u2019Albo degli <strong>autotrasportatori<\/strong> di cose per conto di terzi con mezzi di trasporto ad <strong>elevata sostenibilit\u00e0 ad alimentazione alternativa a metano liquefatto.<\/strong><\/p>\n<h2>Come saranno assegnate le risorse<\/h2>\n<p>I 25 milioni saranno assegnati alle imprese <strong>sotto forma di credito d\u2019imposta<\/strong> nella misura pari al<strong> 20% delle spese sostenute a partire dal 1\u00b0 febbraio 2022 e per tutto l\u2019anno 2022<\/strong>, al netto dell\u2019imposta sul valore aggiunto, per<strong> l\u2019acquisto del gas naturale liquefatto.<\/strong><\/p>\n<p>Il periodo non comprende l\u2019intero anno solare poich\u00e9 l\u2019autorizzazione per ottenere <strong>l\u2019agevolazione da parte della Commissione europea decorre dal 1\u00b0 febbraio 2022.<\/strong><br \/>\nInoltre l\u2019Europa ha fissato <strong>il limite massimo del credito d\u2019imposta concedibile nel 50% dei costi ammissibili<\/strong>, vale a dire fino a <strong>un massimo di 4 milioni di euro per ciascuna impresa. <\/strong>(Costo ammissibile: differenza tra prezzo medio di acquisto del GNL da parte dell\u2019impresa nel 2022 e quello dell\u2019anno 2021 moltiplicato per 1,5)<\/p>\n<p>Le domande per ottenere il beneficio dovranno essere presentate dalle imprese tramite specifica piattaforma.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pubblicato in Gazzetta Ufficiale il decreto interministeriale con le \u201cMisure urgenti per il contenimento dei costi dell\u2019energia elettrica e del gas naturale per lo sviluppo di energie rinnovabili e per il rilancio delle politiche industriali \u2013 Anno 2022&#8243;. Il provvedimento stanzia 25 milioni di euro&#8230;<\/p>\n","protected":false},"author":5,"featured_media":2226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[163,236,218],"class_list":["post-2225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news_esterne","tag-credito-dimposta","tag-gas-naturale-liquefatto","tag-gnl"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/posts\/2225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/comments?post=2225"}],"version-history":[{"count":2,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/posts\/2225\/revisions"}],"predecessor-version":[{"id":2228,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/posts\/2225\/revisions\/2228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/media\/2226"}],"wp:attachment":[{"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/media?parent=2225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/categories?post=2225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.astreitalia.it\/index.php\/wp-json\/wp\/v2\/tags?post=2225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}